{"id":13426,"date":"2018-05-30T14:40:58","date_gmt":"2018-05-30T12:40:58","guid":{"rendered":"https:\/\/gia.mandostudio.hu\/company\/certifications-licenses\/"},"modified":"2026-06-12T11:23:39","modified_gmt":"2026-06-12T09:23:39","slug":"certifications-licenses","status":"publish","type":"page","link":"https:\/\/gia.hu\/en\/company\/certifications-licenses\/","title":{"rendered":"Certifications and Licenses"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13426\" class=\"elementor elementor-13426 elementor-5545\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-767268e e-flex e-con-boxed e-con e-parent\" data-id=\"767268e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-14aa72e e-con-full e-flex e-con e-child\" data-id=\"14aa72e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a3c6e01 e-con-full e-flex e-con e-child\" data-id=\"a3c6e01\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-974d5d0 elementor-widget elementor-widget-image\" data-id=\"974d5d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/gia.hu\/wp-content\/uploads\/2023\/09\/GIA-Hungaria_ISO9001_issue7_2023_HU.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"320\" height=\"453\" src=\"https:\/\/gia.hu\/wp-content\/uploads\/2023\/09\/GIA-Hungaria_ISO9001_issue7_2023_HU_1-scaled-e1694056198983.jpg\" class=\"attachment-full size-full wp-image-12849\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-480b68e e-con-full e-flex e-con e-child\" data-id=\"480b68e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d9ec6d5 elementor-widget elementor-widget-image\" data-id=\"d9ec6d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/gia.hu\/wp-content\/uploads\/2022\/01\/Tanusitvany-GIA-Kft.-MUA-2021_Uj.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"320\" height=\"453\" src=\"https:\/\/gia.hu\/wp-content\/uploads\/2022\/01\/Tanusitvany-GIA-Kft.-MUA-2021_Uj-e1641930717594.jpg\" class=\"attachment-full size-full wp-image-12823\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-73de910 e-con-full e-flex e-con e-child\" data-id=\"73de910\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ed20fd3 elementor-widget elementor-widget-image\" data-id=\"ed20fd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/gia.hu\/wp-content\/uploads\/2024\/11\/384135r3_SCCVCA-tanusitvany_2024-2027.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"320\" height=\"452\" src=\"https:\/\/gia.hu\/wp-content\/uploads\/2024\/11\/384135r3_SCCVCA-tanusitvany_2024-2027.jpg\" class=\"attachment-full size-full wp-image-12880\" alt=\"\" srcset=\"https:\/\/gia.hu\/wp-content\/uploads\/2024\/11\/384135r3_SCCVCA-tanusitvany_2024-2027.jpg 320w, https:\/\/gia.hu\/wp-content\/uploads\/2024\/11\/384135r3_SCCVCA-tanusitvany_2024-2027-212x300.jpg 212w\" sizes=\"(max-width: 320px) 100vw, 320px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c8b9acc e-con-full e-flex e-con e-child\" data-id=\"c8b9acc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1b2e9bb e-con-full e-flex e-con e-child\" data-id=\"1b2e9bb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a0b777 elementor-widget elementor-widget-image\" data-id=\"6a0b777\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/gia.hu\/wp-content\/uploads\/2026\/06\/GIA-Hungaria-Kft.-Tanusitvany-216_2019.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"755\" height=\"1064\" src=\"https:\/\/gia.hu\/wp-content\/uploads\/2026\/06\/tuvtanusitvany_2026-1.webp\" class=\"attachment-full size-full wp-image-15214\" alt=\"\" srcset=\"https:\/\/gia.hu\/wp-content\/uploads\/2026\/06\/tuvtanusitvany_2026-1.webp 755w, https:\/\/gia.hu\/wp-content\/uploads\/2026\/06\/tuvtanusitvany_2026-1-213x300.webp 213w, https:\/\/gia.hu\/wp-content\/uploads\/2026\/06\/tuvtanusitvany_2026-1-727x1024.webp 727w\" sizes=\"(max-width: 755px) 100vw, 755px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-49d9767 e-con-full e-flex e-con e-child\" data-id=\"49d9767\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f356cba elementor-widget elementor-widget-image\" data-id=\"f356cba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/gia.hu\/wp-content\/uploads\/2026\/06\/GIA-Hungaria-Kft._Tanusitvany-8_2018.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"749\" height=\"1029\" src=\"https:\/\/gia.hu\/wp-content\/uploads\/2026\/06\/tuvtanusitvany_2026-2.webp\" class=\"attachment-full size-full wp-image-15216\" alt=\"\" srcset=\"https:\/\/gia.hu\/wp-content\/uploads\/2026\/06\/tuvtanusitvany_2026-2.webp 749w, https:\/\/gia.hu\/wp-content\/uploads\/2026\/06\/tuvtanusitvany_2026-2-218x300.webp 218w, https:\/\/gia.hu\/wp-content\/uploads\/2026\/06\/tuvtanusitvany_2026-2-745x1024.webp 745w\" sizes=\"(max-width: 749px) 100vw, 749px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9b75ea4 e-con-full e-flex e-con e-child\" data-id=\"9b75ea4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4bc4cc4 elementor-widget elementor-widget-image\" data-id=\"4bc4cc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/gia.hu\/wp-content\/uploads\/2026\/06\/GIA-Hungaria-Kft._Tanusitvany-MSZ-EN-ISO-3834-2.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"741\" height=\"1038\" src=\"https:\/\/gia.hu\/wp-content\/uploads\/2026\/06\/tuvtanusitvany_2026-3.webp\" class=\"attachment-full size-full wp-image-15218\" alt=\"\" srcset=\"https:\/\/gia.hu\/wp-content\/uploads\/2026\/06\/tuvtanusitvany_2026-3.webp 741w, https:\/\/gia.hu\/wp-content\/uploads\/2026\/06\/tuvtanusitvany_2026-3-214x300.webp 214w, https:\/\/gia.hu\/wp-content\/uploads\/2026\/06\/tuvtanusitvany_2026-3-731x1024.webp 731w\" sizes=\"(max-width: 741px) 100vw, 741px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-44e42969 e-flex e-con-boxed e-con e-parent\" data-id=\"44e42969\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5fccd976 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"5fccd976\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:50}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>View our public documents<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e984416 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1e984416\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Additional Certifications<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-51ccf5a5 e-con-full e-flex e-con e-child\" data-id=\"51ccf5a5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f733d61 e-con-full e-flex e-con e-child\" data-id=\"f733d61\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-38ae771 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"38ae771\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:150,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-3c6a3b4 e-con-full e-flex e-con e-child\" data-id=\"3c6a3b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a85c995 elementor-widget elementor-widget-heading\" data-id=\"a85c995\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ISO 45001:2018<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-59a528f e-con-full e-flex e-con e-child\" data-id=\"59a528f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0cfa745 e-con-full e-flex e-con e-child\" data-id=\"0cfa745\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-88dc143 elementor-widget elementor-widget-text-editor\" data-id=\"88dc143\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>View or download the document by clicking the icon.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-43fb9fe e-con-full e-flex e-con e-child\" data-id=\"43fb9fe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b34aeb elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"2b34aeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/gia.hu\/wp-content\/uploads\/2023\/09\/HUBUD_000240_GenericCertificate_Final-1.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f09c359 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"f09c359\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:150,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-771a2da e-con-full e-flex e-con e-child\" data-id=\"771a2da\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a5361a4 elementor-widget elementor-widget-heading\" data-id=\"a5361a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ISO 9001:2015<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5b26d51 e-con-full e-flex e-con e-child\" data-id=\"5b26d51\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-85b0b2f e-con-full e-flex e-con e-child\" data-id=\"85b0b2f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ecff346 elementor-widget elementor-widget-text-editor\" data-id=\"ecff346\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>View or download the document by clicking the icon.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec8ba90 e-con-full e-flex e-con e-child\" data-id=\"ec8ba90\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-169c942 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"169c942\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/gia.hu\/wp-content\/uploads\/2023\/09\/GIA-Hungaria_ISO9001_issue7_2023_HU.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cce370e e-con-full e-flex e-con e-child\" data-id=\"cce370e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8f91424 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"8f91424\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:150,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-da335d3 e-con-full e-flex e-con e-child\" data-id=\"da335d3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a5e5b5e elementor-widget elementor-widget-heading\" data-id=\"a5e5b5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ISO 45001:2018 EN<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9250abd e-con-full e-flex e-con e-child\" data-id=\"9250abd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8707dd6 e-con-full e-flex e-con e-child\" data-id=\"8707dd6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ee6f2ff elementor-widget elementor-widget-text-editor\" data-id=\"ee6f2ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>View or download the document by clicking the icon.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-36886eb e-con-full e-flex e-con e-child\" data-id=\"36886eb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8d2166 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"e8d2166\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/gia.hu\/wp-content\/uploads\/2023\/09\/HUBUD_000240_GenericCertificate_Final_EN.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b6ffb4d e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"b6ffb4d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:150,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-ba0e01c e-con-full e-flex e-con e-child\" data-id=\"ba0e01c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f0f1cff elementor-widget elementor-widget-heading\" data-id=\"f0f1cff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ISO 9001:2015 EN<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-07d97e9 e-con-full e-flex e-con e-child\" data-id=\"07d97e9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-31f7718 e-con-full e-flex e-con e-child\" data-id=\"31f7718\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f1d6978 elementor-widget elementor-widget-text-editor\" data-id=\"f1d6978\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>View or download the document by clicking the icon.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0c30279 e-con-full e-flex e-con e-child\" data-id=\"0c30279\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a4811c elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1a4811c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/gia.hu\/wp-content\/uploads\/2023\/09\/GIA-Hungaria_ISO9001_issue7_2023_EN.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-08f2357 e-con-full e-flex e-con e-child\" data-id=\"08f2357\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-260585c e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"260585c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:150,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-023fcc5 e-con-full e-flex e-con e-child\" data-id=\"023fcc5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39152c3 elementor-widget elementor-widget-heading\" data-id=\"39152c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SCCVCA Certificate<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0d493a6 e-con-full e-flex e-con e-child\" data-id=\"0d493a6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c20185e e-con-full e-flex e-con e-child\" data-id=\"c20185e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0877e38 elementor-widget elementor-widget-text-editor\" data-id=\"0877e38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>View or download the document by clicking the icon.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-22971bd e-con-full e-flex e-con e-child\" data-id=\"22971bd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-61d3e49 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"61d3e49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/gia.hu\/wp-content\/uploads\/2024\/11\/384135r3_SCCVCA-tanusitvany_2024-2027.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e80cc3 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"5e80cc3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:150,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-56a0082 e-con-full e-flex e-con e-child\" data-id=\"56a0082\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2adb532 elementor-widget elementor-widget-heading\" data-id=\"2adb532\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ISO 3834-2:2021<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aab289a e-con-full e-flex e-con e-child\" data-id=\"aab289a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4749c38 e-con-full e-flex e-con e-child\" data-id=\"4749c38\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-870f42d elementor-widget elementor-widget-text-editor\" data-id=\"870f42d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>View or download the document by clicking the icon.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e2d0784 e-con-full e-flex e-con e-child\" data-id=\"e2d0784\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bfe9b1b elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"bfe9b1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/gia.hu\/wp-content\/uploads\/2026\/06\/GIA-Hungaria-Kft._Tanusitvany-MSZ-EN-ISO-3834-2.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1318f33 e-con-full e-flex e-con e-child\" data-id=\"1318f33\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8f9c5d3 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"8f9c5d3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:150,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-879c743 e-con-full e-flex e-con e-child\" data-id=\"879c743\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5e45d9 elementor-widget elementor-widget-heading\" data-id=\"c5e45d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">T\u00dcV Certification 216\/2019<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a96ecfd e-con-full e-flex e-con e-child\" data-id=\"a96ecfd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-388682a e-con-full e-flex e-con e-child\" data-id=\"388682a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0598152 elementor-widget elementor-widget-text-editor\" data-id=\"0598152\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>View or download the document by clicking the icon.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-20a13e3 e-con-full e-flex e-con e-child\" data-id=\"20a13e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ccad81 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"2ccad81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/gia.hu\/wp-content\/uploads\/2026\/06\/GIA-Hungaria-Kft.-Tanusitvany-216_2019.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d8e682 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"1d8e682\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:150,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-8a3b697 e-con-full e-flex e-con e-child\" data-id=\"8a3b697\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e8c051 elementor-widget elementor-widget-heading\" data-id=\"1e8c051\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">T\u00dcV min\u0151s\u00edt\u00e9s 8\/2018<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e02a26e e-con-full e-flex e-con e-child\" data-id=\"e02a26e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-62fd733 e-con-full e-flex e-con e-child\" data-id=\"62fd733\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0b843d1 elementor-widget elementor-widget-text-editor\" data-id=\"0b843d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>View or download the document by clicking the icon.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-779e9e3 e-con-full e-flex e-con e-child\" data-id=\"779e9e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74fc0c1 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"74fc0c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/gia.hu\/wp-content\/uploads\/2026\/06\/GIA-Hungaria-Kft._Tanusitvany-8_2018.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1cb4b49 e-con-full e-flex e-con e-child\" data-id=\"1cb4b49\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d17a141 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"d17a141\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:150,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-048dc39 e-con-full e-flex e-con e-child\" data-id=\"048dc39\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9c8a629 elementor-widget elementor-widget-heading\" data-id=\"9c8a629\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Other Approval<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a69c727 e-con-full e-flex e-con e-child\" data-id=\"a69c727\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-08f9706 e-con-full e-flex e-con e-child\" data-id=\"08f9706\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b3113c elementor-widget elementor-widget-text-editor\" data-id=\"4b3113c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>View or download the document by clicking the icon.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c5ff8d0 e-con-full e-flex e-con e-child\" data-id=\"c5ff8d0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-577585b elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"577585b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/gia.hu\/wp-content\/uploads\/2023\/09\/EPAPIR_Bp_szonda-II_30napos_2025.09.30-ig_BP-0103-B-01831-001-2022_hatarozat.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-79f259d e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"79f259d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:150,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-214c4a1 e-con-full e-flex e-con e-child\" data-id=\"214c4a1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c61484 elementor-widget elementor-widget-heading\" data-id=\"7c61484\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">VOC Permit<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a91c4c e-con-full e-flex e-con e-child\" data-id=\"3a91c4c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-172e34a e-con-full e-flex e-con e-child\" data-id=\"172e34a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-42d7fed elementor-widget elementor-widget-text-editor\" data-id=\"42d7fed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>View or download the document by clicking the icon.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4844783 e-con-full e-flex e-con e-child\" data-id=\"4844783\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a695524 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"a695524\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/gia.hu\/wp-content\/uploads\/2023\/09\/EPAPIR_Bp_pg-gazi_hat.eng_2022-20250406-ig_BP-0102-00581-01_2022_.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-76c6d98 e-con-full e-flex e-con e-child\" data-id=\"76c6d98\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-25f3c69 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"25f3c69\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:150,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-67d43e6 e-con-full e-flex e-con e-child\" data-id=\"67d43e6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27cc60c elementor-widget elementor-widget-heading\" data-id=\"27cc60c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Other Approval<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-09bc2a9 e-con-full e-flex e-con e-child\" data-id=\"09bc2a9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ef5e6d8 e-con-full e-flex e-con e-child\" data-id=\"ef5e6d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-020d4bc elementor-widget elementor-widget-text-editor\" data-id=\"020d4bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>View or download the document by clicking the icon.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ccef0e4 e-con-full e-flex e-con e-child\" data-id=\"ccef0e4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c6e4101 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"c6e4101\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/gia.hu\/wp-content\/uploads\/2023\/09\/216_2019IX_5_folyadekok-es-olvadekok.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c0eecc e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"6c0eecc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:150,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4cfaddc e-con-full e-flex e-con e-child\" data-id=\"4cfaddc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8289e34 elementor-widget elementor-widget-heading\" data-id=\"8289e34\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Other Approval<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-21aaf7d e-con-full e-flex e-con e-child\" data-id=\"21aaf7d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3e48b73 e-con-full e-flex e-con e-child\" data-id=\"3e48b73\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a09c437 elementor-widget elementor-widget-text-editor\" data-id=\"a09c437\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>View or download the document by clicking the icon.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ce830ca e-con-full e-flex e-con e-child\" data-id=\"ce830ca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d235a2 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7d235a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.gia.hu\/wp-content\/uploads\/2022\/01\/EPAPIR_Bp_mero_jav.utani30napos_minosites_20241130-ig_BP-0103-B-02089-001-2021_hatarozat_alairt.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-367d1e1 e-con-full e-flex e-con e-child\" data-id=\"367d1e1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-86cbdfc e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"86cbdfc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:150,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-8919327 e-con-full e-flex e-con e-child\" data-id=\"8919327\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-831ab11 elementor-widget elementor-widget-heading\" data-id=\"831ab11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Other Official Decision<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1b78322 e-con-full e-flex e-con e-child\" data-id=\"1b78322\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2179257 e-con-full e-flex e-con e-child\" data-id=\"2179257\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49bee6e elementor-widget elementor-widget-text-editor\" data-id=\"49bee6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>View or download the document by clicking the icon.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0f9014c e-con-full e-flex e-con e-child\" data-id=\"0f9014c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f571136 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f571136\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.gia.hu\/wp-content\/uploads\/2022\/01\/Egyuttmukodesi-megallapos_Szonda-OMH-Labor_BP103-B02479-0022020.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b894c08 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"b894c08\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:150,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-16f99ab e-con-full e-flex e-con e-child\" data-id=\"16f99ab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c466bc elementor-widget elementor-widget-heading\" data-id=\"4c466bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Registration<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8d0797a e-con-full e-flex e-con e-child\" data-id=\"8d0797a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-70f5796 e-con-full e-flex e-con e-child\" data-id=\"70f5796\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5fe05b4 elementor-widget elementor-widget-text-editor\" data-id=\"5fe05b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>View or download the document by clicking the icon.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-70d63eb e-con-full e-flex e-con e-child\" data-id=\"70d63eb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b0f2ae elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"5b0f2ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.gia.hu\/wp-content\/uploads\/2018\/10\/MKIK-kivit-nyilvtart-szam.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f2b8da e-con-full e-flex e-con e-child\" data-id=\"5f2b8da\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9a309b7 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"9a309b7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:150,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-8d00509 e-con-full e-flex e-con e-child\" data-id=\"8d00509\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15aa140 elementor-widget elementor-widget-heading\" data-id=\"15aa140\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Defence Authority Decision<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c19cba e-con-full e-flex e-con e-child\" data-id=\"4c19cba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-19a1448 e-con-full e-flex e-con e-child\" data-id=\"19a1448\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce4fc53 elementor-widget elementor-widget-text-editor\" data-id=\"ce4fc53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>View or download the document by clicking the icon.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-49a5593 e-con-full e-flex e-con e-child\" data-id=\"49a5593\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a86a9c5 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"a86a9c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/www.gia.hu\/wp-content\/uploads\/2018\/10\/374-106-hatarozat.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4784bd4 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"4784bd4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:150,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-42ce375 e-con-full e-flex e-con e-child\" data-id=\"42ce375\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e3b10fc elementor-widget elementor-widget-heading\" data-id=\"e3b10fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Other Certification<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-28c22b1 e-con-full e-flex e-con e-child\" data-id=\"28c22b1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-59dd1b2 e-con-full e-flex e-con e-child\" data-id=\"59dd1b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cbee197 elementor-widget elementor-widget-text-editor\" data-id=\"cbee197\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>View or download the document by clicking the icon.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0db39d3 e-con-full e-flex e-con e-child\" data-id=\"0db39d3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-86e3ca8 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"86e3ca8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/gia.hu\/wp-content\/uploads\/2024\/09\/4310_Uzemanyagmerok_tarolotartalyok-1.2.-fazis-MH.pdf\" target=\"_blank\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-file-download\" viewBox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 136V0H24C10.7 0 0 10.7 0 24v464c0 13.3 10.7 24 24 24h336c13.3 0 24-10.7 24-24V160H248c-13.2 0-24-10.8-24-24zm76.45 211.36l-96.42 95.7c-6.65 6.61-17.39 6.61-24.04 0l-96.42-95.7C73.42 337.29 80.54 320 94.82 320H160v-80c0-8.84 7.16-16 16-16h32c8.84 0 16 7.16 16 16v80h65.18c14.28 0 21.4 17.29 11.27 27.36zM377 105L279.1 7c-4.5-4.5-10.6-7-17-7H256v128h128v-6.1c0-6.3-2.5-12.4-7-16.9z\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>View our public documents Additional Certifications ISO 45001:2018 View or download the document by clicking the icon. ISO 9001:2015 View or download the document by clicking the icon. ISO 45001:2018 EN View or download the document by clicking the icon. ISO 9001:2015 EN View or download the document by clicking the icon. SCCVCA Certificate View [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":13406,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-13426","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Here you can view the certifications, qualifications, and permits of GIA-Hung\u00e1ria Ltd.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/gia.hu\/en\/company\/certifications-licenses\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"GIA-Hung\u00e1ria Kft. | Benzink\u00fattechnika, aut\u00f3mos\u00f3k\" \/>\n\t\t<meta property=\"og:type\" content=\"activity\" \/>\n\t\t<meta property=\"og:title\" content=\"Certifications and Licenses | GIA-Hung\u00e1ria Kft.\" \/>\n\t\t<meta property=\"og:description\" content=\"Here you can view the certifications, qualifications, and permits of GIA-Hung\u00e1ria Ltd.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/gia.hu\/en\/company\/certifications-licenses\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/gia.hu\/wp-content\/uploads\/2023\/03\/gia-technology-gia-hungaria-kft-logo-350px.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/gia.hu\/wp-content\/uploads\/2023\/03\/gia-technology-gia-hungaria-kft-logo-350px.webp\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Certifications and Licenses | GIA-Hung\u00e1ria Kft.\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Here you can view the certifications, qualifications, and permits of GIA-Hung\u00e1ria Ltd.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/gia.hu\/wp-content\/uploads\/2023\/03\/gia-technology-gia-hungaria-kft-logo-350px.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gia.hu\\\/en\\\/company\\\/certifications-licenses\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gia.hu\\\/en\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gia.hu\\\/en\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gia.hu\\\/en\\\/company\\\/#listItem\",\"name\":\"Company\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gia.hu\\\/en\\\/company\\\/#listItem\",\"position\":2,\"name\":\"Company\",\"item\":\"https:\\\/\\\/gia.hu\\\/en\\\/company\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gia.hu\\\/en\\\/company\\\/certifications-licenses\\\/#listItem\",\"name\":\"Certifications and Licenses\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gia.hu\\\/en\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gia.hu\\\/en\\\/company\\\/certifications-licenses\\\/#listItem\",\"position\":3,\"name\":\"Certifications and Licenses\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/gia.hu\\\/en\\\/company\\\/#listItem\",\"name\":\"Company\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gia.hu\\\/en\\\/#organization\",\"name\":\"GIA-Hung\\u00e1ria Kft.\",\"description\":\"Benzink\\u00fattechnika, aut\\u00f3mos\\u00f3k\",\"url\":\"https:\\\/\\\/gia.hu\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/gia.hu\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/gia-technology-gia-hungaria-kft-logo-350px.webp\",\"@id\":\"https:\\\/\\\/gia.hu\\\/en\\\/company\\\/certifications-licenses\\\/#organizationLogo\",\"width\":350,\"height\":420,\"caption\":\"Gia Technology & Service\"},\"image\":{\"@id\":\"https:\\\/\\\/gia.hu\\\/en\\\/company\\\/certifications-licenses\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gia.hu\\\/en\\\/company\\\/certifications-licenses\\\/#webpage\",\"url\":\"https:\\\/\\\/gia.hu\\\/en\\\/company\\\/certifications-licenses\\\/\",\"name\":\"Certifications and Licenses | GIA-Hung\\u00e1ria Kft.\",\"description\":\"Here you can view the certifications, qualifications, and permits of GIA-Hung\\u00e1ria Ltd.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gia.hu\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gia.hu\\\/en\\\/company\\\/certifications-licenses\\\/#breadcrumblist\"},\"datePublished\":\"2018-05-30T14:40:58+02:00\",\"dateModified\":\"2026-06-12T11:23:39+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gia.hu\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/gia.hu\\\/en\\\/\",\"name\":\"GIA-Hung\\u00e1ria Kft.\",\"description\":\"Benzink\\u00fattechnika, aut\\u00f3mos\\u00f3k\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/gia.hu\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Certifications and Licenses | GIA-Hung\u00e1ria Kft.","description":"Here you can view the certifications, qualifications, and permits of GIA-Hung\u00e1ria Ltd.","canonical_url":"https:\/\/gia.hu\/en\/company\/certifications-licenses\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/gia.hu\/en\/company\/certifications-licenses\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/gia.hu\/en\/#listItem","position":1,"name":"Home","item":"https:\/\/gia.hu\/en\/","nextItem":{"@type":"ListItem","@id":"https:\/\/gia.hu\/en\/company\/#listItem","name":"Company"}},{"@type":"ListItem","@id":"https:\/\/gia.hu\/en\/company\/#listItem","position":2,"name":"Company","item":"https:\/\/gia.hu\/en\/company\/","nextItem":{"@type":"ListItem","@id":"https:\/\/gia.hu\/en\/company\/certifications-licenses\/#listItem","name":"Certifications and Licenses"},"previousItem":{"@type":"ListItem","@id":"https:\/\/gia.hu\/en\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/gia.hu\/en\/company\/certifications-licenses\/#listItem","position":3,"name":"Certifications and Licenses","previousItem":{"@type":"ListItem","@id":"https:\/\/gia.hu\/en\/company\/#listItem","name":"Company"}}]},{"@type":"Organization","@id":"https:\/\/gia.hu\/en\/#organization","name":"GIA-Hung\u00e1ria Kft.","description":"Benzink\u00fattechnika, aut\u00f3mos\u00f3k","url":"https:\/\/gia.hu\/en\/","logo":{"@type":"ImageObject","url":"https:\/\/gia.hu\/wp-content\/uploads\/2023\/03\/gia-technology-gia-hungaria-kft-logo-350px.webp","@id":"https:\/\/gia.hu\/en\/company\/certifications-licenses\/#organizationLogo","width":350,"height":420,"caption":"Gia Technology & Service"},"image":{"@id":"https:\/\/gia.hu\/en\/company\/certifications-licenses\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/gia.hu\/en\/company\/certifications-licenses\/#webpage","url":"https:\/\/gia.hu\/en\/company\/certifications-licenses\/","name":"Certifications and Licenses | GIA-Hung\u00e1ria Kft.","description":"Here you can view the certifications, qualifications, and permits of GIA-Hung\u00e1ria Ltd.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/gia.hu\/en\/#website"},"breadcrumb":{"@id":"https:\/\/gia.hu\/en\/company\/certifications-licenses\/#breadcrumblist"},"datePublished":"2018-05-30T14:40:58+02:00","dateModified":"2026-06-12T11:23:39+02:00"},{"@type":"WebSite","@id":"https:\/\/gia.hu\/en\/#website","url":"https:\/\/gia.hu\/en\/","name":"GIA-Hung\u00e1ria Kft.","description":"Benzink\u00fattechnika, aut\u00f3mos\u00f3k","inLanguage":"en-US","publisher":{"@id":"https:\/\/gia.hu\/en\/#organization"}}]},"og:locale":"en_US","og:site_name":"GIA-Hung\u00e1ria Kft. | Benzink\u00fattechnika, aut\u00f3mos\u00f3k","og:type":"activity","og:title":"Certifications and Licenses | GIA-Hung\u00e1ria Kft.","og:description":"Here you can view the certifications, qualifications, and permits of GIA-Hung\u00e1ria Ltd.","og:url":"https:\/\/gia.hu\/en\/company\/certifications-licenses\/","og:image":"https:\/\/gia.hu\/wp-content\/uploads\/2023\/03\/gia-technology-gia-hungaria-kft-logo-350px.webp","og:image:secure_url":"https:\/\/gia.hu\/wp-content\/uploads\/2023\/03\/gia-technology-gia-hungaria-kft-logo-350px.webp","twitter:card":"summary","twitter:title":"Certifications and Licenses | GIA-Hung\u00e1ria Kft.","twitter:description":"Here you can view the certifications, qualifications, and permits of GIA-Hung\u00e1ria Ltd.","twitter:image":"https:\/\/gia.hu\/wp-content\/uploads\/2023\/03\/gia-technology-gia-hungaria-kft-logo-350px.webp"},"aioseo_meta_data":{"post_id":"13426","title":null,"description":"Here you can view the certifications, qualifications, and permits of GIA-Hung\u00e1ria Ltd. ","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"activity","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"summary","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-07-04 08:28:00","updated":"2026-06-12 09:25:46","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/gia.hu\/en\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u2022<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/gia.hu\/en\/company\/\" title=\"Company\">Company<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u2022<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCertifications and Licenses\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/gia.hu\/en\/"},{"label":"Company","link":"https:\/\/gia.hu\/en\/company\/"},{"label":"Certifications and Licenses","link":"https:\/\/gia.hu\/en\/company\/certifications-licenses\/"}],"_links":{"self":[{"href":"https:\/\/gia.hu\/en\/wp-json\/wp\/v2\/pages\/13426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gia.hu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/gia.hu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/gia.hu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gia.hu\/en\/wp-json\/wp\/v2\/comments?post=13426"}],"version-history":[{"count":3,"href":"https:\/\/gia.hu\/en\/wp-json\/wp\/v2\/pages\/13426\/revisions"}],"predecessor-version":[{"id":15229,"href":"https:\/\/gia.hu\/en\/wp-json\/wp\/v2\/pages\/13426\/revisions\/15229"}],"up":[{"embeddable":true,"href":"https:\/\/gia.hu\/en\/wp-json\/wp\/v2\/pages\/13406"}],"wp:attachment":[{"href":"https:\/\/gia.hu\/en\/wp-json\/wp\/v2\/media?parent=13426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}